{"id":1,"date":"2019-06-29T18:34:00","date_gmt":"2019-06-29T18:34:00","guid":{"rendered":"http:\/\/sosracismonafarroa.com\/\/?p=1"},"modified":"2020-06-02T21:42:58","modified_gmt":"2020-06-02T21:42:58","slug":"la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea","status":"publish","type":"post","link":"https:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/","title":{"rendered":"La detenci\u00f3n de Floyd hace recordar la de Ndiaye, fallecido luego en la comisar\u00eda de Iru\u00f1ea"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1\" class=\"elementor elementor-1\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16e4059f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16e4059f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d05c2e8\" data-id=\"1d05c2e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b31f14c elementor-widget elementor-widget-text-editor\" data-id=\"7b31f14c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><!-- wp:paragraph --><\/p>\n<p>Texto de:\u00a0<a href=\"https:\/\/www.naiz.eus\/es\/actualidad\/noticia\/20200601\/la-muerte-de-floyd-recuerda-el-caso-de-elhadji-ndiaye-senegales-fallecido-en-la-comisaria-de-irunea\" target=\"_blank\" rel=\"noreferrer noopener\">www.naiz.eus<\/a> La muerte del estadounidense de raza negra George Floyd a manos de un agente blanco en Mine\u00e1polis est\u00e1 provocando una convulsi\u00f3n mundial. En Iru\u00f1ea ha hecho recordar el fallecimiento de Elhadji Ndiaye, senegal\u00e9s que muri\u00f3 hace cuatro a\u00f1os en dependencias policiales de la capital tras una detenci\u00f3n muy similar. La raz\u00f3n no fue aclarada.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><a href=\"https:\/\/www.naiz.eus\/eu\/actualidad\/noticia\/20200601\/las-protestas-por-la-muerte-de-george-floyd-llegan-a-las-puertas-de-la-casa-blanca\">Las imagenes de las protestas de los estadounidenses por la muerte de George Floyd<\/a>, hombre de raza negra, a manos de un agente blanco en Mine\u00e1polis, est\u00e1n recorriendo el mundo. Este \u00faltimo episodio racista por parte de la polic\u00eda no es nuevo en los Estados Unidos. Se asemeja, entre otros, al caso de Eric Garner que tambi\u00e9n falleci\u00f3 por asfixia en una actuaci\u00f3n policial hace seis a\u00f1os. Y en Euskal Herria tambi\u00e9n tiene un antecedente reciente.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>En Iru\u00f1ea sigue fresco en la memoria\u00a0<a href=\"https:\/\/www.naiz.eus\/eu\/actualidad\/noticia\/20161025\/muere-un-detenido-en-la-comisaria-de-la-policia-espanola-en-irunea\">el fallecimiento de Elhadji Ndiaye<\/a>, hombre de origen senegal\u00e9s que muri\u00f3 en octubre de 2016 en las dependencias de la Jefatura Superior de Polic\u00eda de Iru\u00f1ea despu\u00e9s de ser arrestado en el barrio iruindarra de Arrotxapea. As\u00ed lo ha recordado la asociaci\u00f3n SOS Racismo de Nafarroa a trav\u00e9s de este tuit:<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>El Tribunal Superior de Justicia de Navarra (TSJN) envi\u00f3 a la prensa un escueto comunicado en el que se\u00f1alaba que\u00a0<a href=\"https:\/\/www.naiz.eus\/eu\/actualidad\/noticia\/20161026\/la-autopsia-del-muerto-en-la-comisaria-de-irunea-descarta-signos-de-violencia\">la autopsia practicada al fallecido \u00abdescarta la presencia de signos de violencia\u00bb<\/a>. Nunca se pudo esclarecer al 100% la causa de su muerte y\u00a0<a href=\"https:\/\/www.naiz.eus\/eu\/actualidad\/noticia\/20161126\/cientos-de-personas-exigen-en-irunea-el-esclarecimiento-de-la-muerte-de-elhadji-ndiaye-en-comisaria\">cientos de personas, convocadas por la comunidad senegalesa de Nafarroa y diversos colectivos sociales, denunciaron lo sucedido.<br \/><\/a>Sobre su detenci\u00f3n en la calle Marcelo Zelaieta existen varios v\u00eddeos y del posterior traslado a la comisar\u00eda de la Polic\u00eda Nacional espa\u00f1ola\u00a0<a href=\"https:\/\/www.naiz.eus\/eu\/actualidad\/noticia\/20161028\/testigos-dicen-que-la-policia-se-llevo-inconsciente-al-detenido-en-arrotxapea\">hay diversas versiones<\/a>, tal y como recogi\u00f3 en su d\u00eda el periodista de NAIZ Be\u00f1at Zaldua.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>El relato policial tres d\u00edas despu\u00e9s del suceso aseguraba que, tras resistirse duramente a su detenci\u00f3n, Ndiaye fue reducido y trasladado a comisar\u00eda, donde en un momento dado un polic\u00eda se habr\u00eda dado cuenta de que el arrestado no respiraba. Sin embargo, dos testigos que presenciaron en directo la detenci\u00f3n y que prefirieron mantener el anonimato aseguraron a este medio de comunicaci\u00f3n que la Polic\u00eda se llev\u00f3 al detenido ya inconsciente.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Explicaron que dos agentes de paisano dieron el alto a Ndiaye, que iba en moto y que pregunt\u00f3 por qu\u00e9 lo paraban. \u00abEl polic\u00eda insist\u00eda en que se identificase y el chico respond\u00eda que por qu\u00e9 lo ten\u00eda que hacer\u00bb, relat\u00f3 uno de los testigos, quien a\u00f1adi\u00f3 que la tensi\u00f3n creci\u00f3 hasta llegar a las manos. Confirm\u00f3 que Ndiaye se resisti\u00f3 fuertemente y que los tres acabaron en el suelo. Pero la versi\u00f3n cambia al llegar al final de la escena en Marcelo Zelaieta.<br \/><br \/>La afirmaci\u00f3n policial recogida por la prensa dice que una vez en el coche se mostr\u00f3 menos agresivo. La versi\u00f3n de los dos testigos es otra: \u00abCuando llegaron los otros agentes lo inmovilizaron en el suelo sin problema. Durante un rato pudimos o\u00edr los gritos de dolor del chico, pero de repente, en un momento, se call\u00f3. Cuando lo subieron al coche estaba ya inconsciente, como muerto\u00bb.<\/p>\n<p><!-- \/wp:paragraph --><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Texto de:\u00a0www.naiz.eus La muerte del estadounidense de raza negra George Floyd a manos de un agente blanco en Mine\u00e1polis est\u00e1 provocando una convulsi\u00f3n mundial. En Iru\u00f1ea ha hecho recordar el fallecimiento de Elhadji Ndiaye, senegal\u00e9s que muri\u00f3 hace cuatro a\u00f1os en dependencias policiales de la capital tras una detenci\u00f3n muy <a href=\"https:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\" class=\"btn-link\">Seguir leyendo<i class=\"ion-ios-arrow-right\"><\/i><\/a><\/p>\n","protected":false},"author":2,"featured_media":38,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La detenci\u00f3n de Floyd hace recordar la de Ndiaye, fallecido luego en la comisar\u00eda de Iru\u00f1ea - SOS RACISMO NAFARROA<\/title>\n<link rel=\"canonical\" href=\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La detenci\u00f3n de Floyd hace recordar la de Ndiaye, fallecido luego en la comisar\u00eda de Iru\u00f1ea - SOS RACISMO NAFARROA\" \/>\n<meta property=\"og:description\" content=\"Texto de:\u00a0www.naiz.eus La muerte del estadounidense de raza negra George Floyd a manos de un agente blanco en Mine\u00e1polis est\u00e1 provocando una convulsi\u00f3n mundial. En Iru\u00f1ea ha hecho recordar el fallecimiento de Elhadji Ndiaye, senegal\u00e9s que muri\u00f3 hace cuatro a\u00f1os en dependencias policiales de la capital tras una detenci\u00f3n muy Seguir leyendo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\" \/>\n<meta property=\"og:site_name\" content=\"SOS RACISMO NAFARROA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sos.nafarroa\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-29T18:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-02T21:42:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sosracismonafarroa.es\/wp-content\/uploads\/2019\/01\/whatsapp-20image-202020-05-30-20at-2019-30-05.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SOSracismoNafar\" \/>\n<meta name=\"twitter:site\" content=\"@SOSracismoNafar\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data1\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sosracismonafarroa.es\/#website\",\"url\":\"https:\/\/sosracismonafarroa.es\/\",\"name\":\"SOS RACISMO NAFARROA\",\"description\":\"Desde 1992 contra el racismo institucional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/sosracismonafarroa.es\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/sosracismonafarroa.es\/wp-content\/uploads\/2019\/01\/whatsapp-20image-202020-05-30-20at-2019-30-05.jpeg\",\"width\":960,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/#webpage\",\"url\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\",\"name\":\"La detenci\\u00f3n de Floyd hace recordar la de Ndiaye, fallecido luego en la comisar\\u00eda de Iru\\u00f1ea - SOS RACISMO NAFARROA\",\"isPartOf\":{\"@id\":\"https:\/\/sosracismonafarroa.es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/#primaryimage\"},\"datePublished\":\"2019-06-29T18:34:00+00:00\",\"dateModified\":\"2020-06-02T21:42:58+00:00\",\"author\":{\"@id\":\"https:\/\/sosracismonafarroa.es\/#\/schema\/person\/979751911885c8dfb6652b8357c2e3c9\"},\"breadcrumb\":{\"@id\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sosracismonafarroa.es\/\",\"url\":\"https:\/\/sosracismonafarroa.es\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\",\"url\":\"http:\/\/sosracismonafarroa.es\/index.php\/2019\/06\/29\/la-detencion-de-floyd-hace-recordar-la-de-ndiaye-fallecido-luego-en-la-comisaria-de-irunea\/\",\"name\":\"La detenci\\u00f3n de Floyd hace recordar la de Ndiaye, fallecido luego en la comisar\\u00eda de Iru\\u00f1ea\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/sosracismonafarroa.es\/#\/schema\/person\/979751911885c8dfb6652b8357c2e3c9\",\"name\":\"Sos Racismo Nafarroa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/sosracismonafarroa.es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/87ce1f3eb957327a5e0cdda02214fdee?s=96&d=mm&r=g\",\"caption\":\"Sos Racismo Nafarroa\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/posts\/1"}],"collection":[{"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/comments?post=1"}],"version-history":[{"count":9,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions"}],"predecessor-version":[{"id":222,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/posts\/1\/revisions\/222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/media\/38"}],"wp:attachment":[{"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/media?parent=1"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/categories?post=1"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosracismonafarroa.es\/index.php\/wp-json\/wp\/v2\/tags?post=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}